{"id":275,"count":1,"description":"","link":"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/","name":"salads","slug":"salads","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>salads<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"salads\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/\" \/>\n<meta property=\"og:site_name\" content=\"Neolife\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/\",\"url\":\"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/\",\"name\":\"salads\",\"isPartOf\":{\"@id\":\"https:\/\/www.neolifesalud.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Neolife\",\"item\":\"https:\/\/www.neolifesalud.com\/en\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"salads\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.neolifesalud.com\/en\/#website\",\"url\":\"https:\/\/www.neolifesalud.com\/en\/\",\"name\":\"Neolife\",\"description\":\"Medicina preventiva antiaging\",\"publisher\":{\"@id\":\"https:\/\/www.neolifesalud.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.neolifesalud.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.neolifesalud.com\/en\/#organization\",\"name\":\"Neolife\",\"url\":\"https:\/\/www.neolifesalud.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.neolifesalud.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.neolifesalud.com\/wp-content\/uploads\/Logo_Neolife_2025-1-scaled.png\",\"contentUrl\":\"https:\/\/www.neolifesalud.com\/wp-content\/uploads\/Logo_Neolife_2025-1-scaled.png\",\"width\":2560,\"height\":855,\"caption\":\"Neolife\"},\"image\":{\"@id\":\"https:\/\/www.neolifesalud.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"salads","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/","og_locale":"en_US","og_type":"article","og_title":"salads","og_url":"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/","og_site_name":"Neolife","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/","url":"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/","name":"salads","isPartOf":{"@id":"https:\/\/www.neolifesalud.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.neolifesalud.com\/en\/blog\/tag\/salads\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Neolife","item":"https:\/\/www.neolifesalud.com\/en\/home-2\/"},{"@type":"ListItem","position":2,"name":"salads"}]},{"@type":"WebSite","@id":"https:\/\/www.neolifesalud.com\/en\/#website","url":"https:\/\/www.neolifesalud.com\/en\/","name":"Neolife","description":"Medicina preventiva antiaging","publisher":{"@id":"https:\/\/www.neolifesalud.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neolifesalud.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.neolifesalud.com\/en\/#organization","name":"Neolife","url":"https:\/\/www.neolifesalud.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.neolifesalud.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.neolifesalud.com\/wp-content\/uploads\/Logo_Neolife_2025-1-scaled.png","contentUrl":"https:\/\/www.neolifesalud.com\/wp-content\/uploads\/Logo_Neolife_2025-1-scaled.png","width":2560,"height":855,"caption":"Neolife"},"image":{"@id":"https:\/\/www.neolifesalud.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.neolifesalud.com\/en\/wp-json\/wp\/v2\/tags\/275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neolifesalud.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.neolifesalud.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.neolifesalud.com\/en\/wp-json\/wp\/v2\/posts?tags=275"},{"href":"https:\/\/www.neolifesalud.com\/en\/wp-json\/wp\/v2\/shared_file?tags=275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}